{"id":5709,"date":"2026-01-27T15:49:00","date_gmt":"2026-01-27T18:49:00","guid":{"rendered":"https:\/\/catalog.hcrepresentations.com\/product\/oleo-hidratante-cutinutri-30ml\/"},"modified":"2026-08-04T09:56:07","modified_gmt":"2026-08-04T12:56:07","slug":"oleo-hidratante-cutinutri-30ml","status":"publish","type":"product","link":"https:\/\/catalog.hcrepresentations.com\/pt\/produto\/oleo-hidratante-cutinutri-30ml\/","title":{"rendered":"\u00d3leo Hidratante Cutinutri 30ml"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>O CutiNutri \u00e9 um \u00f3leo de cut\u00edculas de alto desempenho, criado para oferecer nutri\u00e7\u00e3o, hidrata\u00e7\u00e3o e<br \/>\n prote\u00e7\u00e3o para suas m\u00e3os por completo.<br \/>\n Para que serve o CutiNutri?<br \/>\n Com sua f\u00f3rmula inovadora e mat\u00e9rias primas de alta qualidade, previne o envelhecimento precoce,<br \/>\n clareia e uniformiza a pele, fortalece as unhas e melhora a elasticidade da pele.<br \/>\n Quando usar o CutiNutri?<br \/>\n O \u00f3leo de cut\u00edculas da Bluwe \u00e9 perfeito para ser utilizado em qualquer momento do dia e \u00e9 compat\u00edvel<br \/>\n com todos os tipos de pele.<br \/>\n Ele \u00e9 realmente um produto de cuidados com a pele para as m\u00e3os que deveria estar em sua mesa, bolsa e banheiro.<br \/>\n Os resultados imediatos e a longo prazo s\u00e3o surpreendentes, ent\u00e3o, seja em procedimentos de unhas<br \/>\n gel ou como um tratamento de skincare, ele \u00e9 super recomendado.<\/p>","protected":false},"featured_media":4817,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[98],"product_tag":[],"class_list":["post-5709","product","type-product","status-publish","has-post-thumbnail","product_cat-bluwe","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/catalog.hcrepresentations.com\/pt\/wp-json\/wp\/v2\/product\/5709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catalog.hcrepresentations.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/catalog.hcrepresentations.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/catalog.hcrepresentations.com\/pt\/wp-json\/wp\/v2\/comments?post=5709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catalog.hcrepresentations.com\/pt\/wp-json\/wp\/v2\/media\/4817"}],"wp:attachment":[{"href":"https:\/\/catalog.hcrepresentations.com\/pt\/wp-json\/wp\/v2\/media?parent=5709"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/catalog.hcrepresentations.com\/pt\/wp-json\/wp\/v2\/product_brand?post=5709"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/catalog.hcrepresentations.com\/pt\/wp-json\/wp\/v2\/product_cat?post=5709"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/catalog.hcrepresentations.com\/pt\/wp-json\/wp\/v2\/product_tag?post=5709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}